{"id":486,"date":"2020-07-03T15:04:51","date_gmt":"2020-07-03T13:04:51","guid":{"rendered":"http:\/\/www.allurealps.com\/about\/"},"modified":"2026-05-11T18:20:03","modified_gmt":"2026-05-11T16:20:03","slug":"about","status":"publish","type":"page","link":"https:\/\/www.allurealps.com\/it\/about\/","title":{"rendered":"About us"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kcc2d5k0-78cdd6c5eb07a996c64e9ee3525db423\">\n.avia-section.av-kcc2d5k0-78cdd6c5eb07a996c64e9ee3525db423{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/07\/Allure-Alps-Sled-race-header-3.jpg);\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-kcc2d5k0-78cdd6c5eb07a996c64e9ee3525db423 alternate_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-full-stretch avia-bg-style-scroll av-minimum-height av-minimum-height-custom av-height-custom  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_px='580'><div class='container av-section-cont-open' style='height:580px'><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-486'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1jrkt-00604e8f7806f6e14fce11ed03fb7d55\">\n.flex_column.av-1jrkt-00604e8f7806f6e14fce11ed03fb7d55{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1jrkt-00604e8f7806f6e14fce11ed03fb7d55 av_one_full  avia-builder-el-1  el_before_av_one_full  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kq8ex5iv-123049184c3e41513403e6e95f99b671\">\n#top .av-special-heading.av-kq8ex5iv-123049184c3e41513403e6e95f99b671{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-kq8ex5iv-123049184c3e41513403e6e95f99b671 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-kq8ex5iv-123049184c3e41513403e6e95f99b671 .av-subheading{\nfont-size:24px;\n}\n<\/style>\n<div  class='av-special-heading av-kq8ex5iv-123049184c3e41513403e6e95f99b671 av-special-heading-h1 blockquote modern-quote modern-centered  avia-builder-el-2  avia-builder-el-no-sibling '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Chi siamo<\/h1><div class='av-subheading av-subheading_below'><p>Progettiamo e realizziamo esperienze ed eventi di alto livello nelle Alpi, combinando visione creativa, competenza operativa e una profonda conoscenza dell\u2019ambiente montano.<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-12jwh-3af9553dd2713edb7a7812882fcbbffa\">\n.flex_column.av-12jwh-3af9553dd2713edb7a7812882fcbbffa{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-12jwh-3af9553dd2713edb7a7812882fcbbffa av_one_full  avia-builder-el-3  el_after_av_one_full  avia-builder-el-last  box-get-in first flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kcc3rvnx-070a2399d6f28834a7d57e85cffe5354\">\n#top .av_textblock_section.av-kcc3rvnx-070a2399d6f28834a7d57e85cffe5354 .avia_textblock{\nfont-size:14px;\n}\n<\/style>\n<section  class='av_textblock_section av-kcc3rvnx-070a2399d6f28834a7d57e85cffe5354 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: left;\"><a href=\"mailto:info@allurealps.com\">Vuoi saperne di pi\u00f9?<br \/>\n<span class=\"get-in-contact\">Scrivici e ti risponderemo<\/span><\/a><\/p>\n<\/div><\/section><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-1q8rd-07f85a64774d5d78fb39f1999fd4cafb main_color avia-section-large avia-no-border-styling  avia-builder-el-5  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-486'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1228h-9853ff6edb0a9a79c0e8a1e08d73d9eb\">\n.flex_column.av-1228h-9853ff6edb0a9a79c0e8a1e08d73d9eb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1228h-9853ff6edb0a9a79c0e8a1e08d73d9eb av_one_fifth  avia-builder-el-6  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1228h-14-4bdbe70e721d057cede61f1415e3dfe1\">\n.flex_column.av-1228h-14-4bdbe70e721d057cede61f1415e3dfe1{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1228h-14-4bdbe70e721d057cede61f1415e3dfe1 av_three_fifth  avia-builder-el-7  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-kcel4ow2-3c8b566c930b29db04a5927d9555aa83 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Missione<\/h2>\n<p data-start=\"2062\" data-end=\"2196\">In Allure Alps, ogni esperienza nasce da una visione e prende forma attraverso un equilibrio tra creativit\u00e0, esperienza ed esecuzione.<\/p>\n<p data-start=\"2198\" data-end=\"2353\">Ispirati dal carattere unico delle Alpi, progettiamo esperienze su misura che mettono in relazione persone, luoghi ed emozioni in modo naturale e coerente.<\/p>\n<p data-start=\"2355\" data-end=\"2541\">Dai momenti privati pi\u00f9 esclusivi agli eventi aziendali pi\u00f9 complessi, il nostro lavoro \u00e8 guidato da attenzione al dettaglio, precisione operativa e una costante ricerca dell\u2019eccellenza.<\/p>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1228h-13-2bc41730ff8532eda0c8fa7b897fd418\">\n.flex_column.av-1228h-13-2bc41730ff8532eda0c8fa7b897fd418{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1228h-13-2bc41730ff8532eda0c8fa7b897fd418 av_one_fifth  avia-builder-el-9  el_after_av_three_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_3'  class='avia-section av-kc6bzpup-7f5c531ee6f4e1d139a141ab608eacbf main_color avia-section-huge avia-no-border-styling  avia-builder-el-10  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-486'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc6byz13-9f4ae5f7aa1e7857bcb8d8ad7981b444\">\n.flex_column.av-kc6byz13-9f4ae5f7aa1e7857bcb8d8ad7981b444{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-kc6byz13-9f4ae5f7aa1e7857bcb8d8ad7981b444 av_one_half  avia-builder-el-11  el_before_av_one_full  avia-builder-el-first  box-on-photo first no_margin flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-12x3l-bb7345595b418e39bcd0ffb6470fcd33\">\n#top .av-special-heading.av-12x3l-bb7345595b418e39bcd0ffb6470fcd33{\npadding-bottom:0;\n}\nbody .av-special-heading.av-12x3l-bb7345595b418e39bcd0ffb6470fcd33 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-12x3l-bb7345595b418e39bcd0ffb6470fcd33 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-12x3l-bb7345595b418e39bcd0ffb6470fcd33 av-special-heading-h2 blockquote modern-quote  avia-builder-el-12  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >Capacit\u00e0 \/ Differenziazione<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-kc6bxrh2-c48d2f6b505c8d2f001abb4c313a85c9 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p data-start=\"2572\" data-end=\"2701\">Ci\u00f2 che rende unico il nostro approccio \u00e8 la combinazione tra direzione creativa e una profonda competenza negli ambienti alpini.<\/p>\n<p data-start=\"2703\" data-end=\"2913\">Il nostro background operativo in montagna ci permette di progettare e realizzare esperienze anche in contesti complessi, dove logistica, accessi e condizioni ambientali diventano parte integrante del progetto.<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc6byz13-10-77feb691612874466aa5191b961b6948\">\n.flex_column.av-kc6byz13-10-77feb691612874466aa5191b961b6948{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-kc6byz13-10-77feb691612874466aa5191b961b6948 av_one_full  avia-builder-el-14  el_after_av_one_half  avia-builder-el-last  box-img first flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc6cdnrb-ff7ea4d8955746abe1e645d3be63a0d2\">\n.avia-image-container.av-kc6cdnrb-ff7ea4d8955746abe1e645d3be63a0d2 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kc6cdnrb-ff7ea4d8955746abe1e645d3be63a0d2 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kc6cdnrb-ff7ea4d8955746abe1e645d3be63a0d2 av-styling- avia-align-center  avia-builder-el-15  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2582 avia-img-lazy-loading-not-2582 avia_image ' src=\"https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/05\/Allure-Alps-Winter-picnic-copertina-8-1.jpg\" alt='' title='Allure-Alps---Winter-picnic-copertina-8'  height=\"570\" width=\"1380\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/05\/Allure-Alps-Winter-picnic-copertina-8-1.jpg 1380w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/05\/Allure-Alps-Winter-picnic-copertina-8-1-300x124.jpg 300w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/05\/Allure-Alps-Winter-picnic-copertina-8-1-1030x425.jpg 1030w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/05\/Allure-Alps-Winter-picnic-copertina-8-1-768x317.jpg 768w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/05\/Allure-Alps-Winter-picnic-copertina-8-1-705x291.jpg 705w\" sizes=\"(max-width: 1380px) 100vw, 1380px\" \/><\/div><\/div><\/div><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_4'  class='avia-section av-moio6wuh-e76372818664ceedc0029cf50ff07fca main_color avia-section-huge avia-no-border-styling  avia-builder-el-16  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-486'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3val-25a37246a560162f7b8379daf32f44d2\">\n.flex_column.av-3val-25a37246a560162f7b8379daf32f44d2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-3val-25a37246a560162f7b8379daf32f44d2 av_one_full  avia-builder-el-17  el_before_av_one_half  avia-builder-el-first  box-img first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-moioedv3-627b51bb2df767b65a40d24210f92450\">\n.avia-image-container.av-moioedv3-627b51bb2df767b65a40d24210f92450 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-moioedv3-627b51bb2df767b65a40d24210f92450 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-moioedv3-627b51bb2df767b65a40d24210f92450 av-styling- avia-align-center  avia-builder-el-18  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2965 avia-img-lazy-loading-not-2965 avia_image ' src=\"https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/07\/Allure-Alps-Sled-race-gallery-8.jpg\" alt='' title='Allure-Alps---Sled-race-gallery-8'  height=\"466\" width=\"700\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/07\/Allure-Alps-Sled-race-gallery-8.jpg 700w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2025\/07\/Allure-Alps-Sled-race-gallery-8-300x200.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-moio922m-2d39cf37dd8897becb4ce43aafe4e223\">\n.flex_column.av-moio922m-2d39cf37dd8897becb4ce43aafe4e223{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-moio922m-2d39cf37dd8897becb4ce43aafe4e223 av_one_half  avia-builder-el-19  el_after_av_one_full  avia-builder-el-last  box-on-photo first no_margin flex_column_div av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-moiob4oz-5bff9b8d86cbd807f770bd6cbb996394\">\n#top .av-special-heading.av-moiob4oz-5bff9b8d86cbd807f770bd6cbb996394{\npadding-bottom:0;\n}\nbody .av-special-heading.av-moiob4oz-5bff9b8d86cbd807f770bd6cbb996394 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-moiob4oz-5bff9b8d86cbd807f770bd6cbb996394 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-moiob4oz-5bff9b8d86cbd807f770bd6cbb996394 av-special-heading-h2 blockquote modern-quote  avia-builder-el-20  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >Approccio<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-moioawh1-56485a75b0b9281765b1151dabaeae5b '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p data-start=\"2937\" data-end=\"2989\">Ogni progetto nasce da un processo chiaro e diretto:<\/p>\n<ul data-start=\"2991\" data-end=\"3074\">\n<li data-section-id=\"vyoc6y\" data-start=\"2991\" data-end=\"3017\">comprendere la visione<\/li>\n<li data-section-id=\"e1wmy3\" data-start=\"3018\" data-end=\"3043\">definire l\u2019esperienza<\/li>\n<li data-section-id=\"1kba2ok\" data-start=\"3044\" data-end=\"3074\">realizzarla con precisione<\/li>\n<\/ul>\n<p data-start=\"3076\" data-end=\"3210\">Lavoriamo a stretto contatto con i nostri clienti per trasformare un\u2019idea in un\u2019esperienza fluida, immersiva e perfettamente eseguita.<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_5'  class='avia-section av-1hwlt-c94d830ed79a62ee0295da3a44b7f246 main_color avia-section-large avia-no-border-styling  avia-builder-el-22  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-486'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-15ryd-02ec76ab096c5e92089eeff2decef420 sc-av_one_half av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-15ryd-02ec76ab096c5e92089eeff2decef420\">\n.flex_column.av-15ryd-02ec76ab096c5e92089eeff2decef420{\nborder-radius:5px 5px 5px 5px;\npadding:0px 0px 0px 0px;\nbackground-color:#f5f5f5;\n}\n<\/style>\n<div  class='flex_column av-15ryd-02ec76ab096c5e92089eeff2decef420 av_one_half  avia-builder-el-23  el_before_av_one_half  avia-builder-el-first  column-team first flex_column_table_cell av-equal-height-column av-align-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc6cdnrb-9-0056c13ac397241afa6687b6b087c83b\">\n.avia-image-container.av-kc6cdnrb-9-0056c13ac397241afa6687b6b087c83b img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kc6cdnrb-9-0056c13ac397241afa6687b6b087c83b .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kc6cdnrb-9-0056c13ac397241afa6687b6b087c83b av-styling- avia-align-center  avia-builder-el-24  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-3031 avia-img-lazy-loading-not-3031 avia_image ' src=\"https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/J4.jpg\" alt='' title='J4'  height=\"1000\" width=\"1000\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/J4.jpg 1000w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/J4-300x300.jpg 300w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/J4-80x80.jpg 80w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/J4-768x768.jpg 768w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/J4-36x36.jpg 36w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/J4-180x180.jpg 180w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/J4-705x705.jpg 705w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mp1epa0r-efbed1f467390f5bae2b7f007fafd9c4\">\n#top .av_textblock_section.av-mp1epa0r-efbed1f467390f5bae2b7f007fafd9c4 .avia_textblock{\nfont-size:14px;\n}\n<\/style>\n<section  class='av_textblock_section av-mp1epa0r-efbed1f467390f5bae2b7f007fafd9c4 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock text-team'  itemprop=\"text\" ><h4>Jean Edouard Hardy<\/h4>\n<p class=\"titolo-elenco-experience\">Founder<\/p>\n<\/div><\/section><\/p><\/div><div class='av-flex-placeholder'><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-15ryd-5-9bf9fdf9efd984725deda888977628c8\">\n.flex_column.av-15ryd-5-9bf9fdf9efd984725deda888977628c8{\nborder-radius:5px 5px 5px 5px;\npadding:0px 0px 0px 0px;\nbackground-color:#f5f5f5;\n}\n<\/style>\n<div  class='flex_column av-15ryd-5-9bf9fdf9efd984725deda888977628c8 av_one_half  avia-builder-el-26  el_after_av_one_half  avia-builder-el-last  column-team flex_column_table_cell av-equal-height-column av-align-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc6cdnrb-4-40926f7ece8b7e3c8308540214b0304b\">\n.avia-image-container.av-kc6cdnrb-4-40926f7ece8b7e3c8308540214b0304b img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kc6cdnrb-4-40926f7ece8b7e3c8308540214b0304b .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kc6cdnrb-4-40926f7ece8b7e3c8308540214b0304b av-styling- avia-align-center  avia-builder-el-27  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-3032 avia-img-lazy-loading-not-3032 avia_image ' src=\"https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/A1.jpg\" alt='' title='A1'  height=\"1000\" width=\"1000\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/A1.jpg 1000w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/A1-300x300.jpg 300w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/A1-80x80.jpg 80w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/A1-768x768.jpg 768w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/A1-36x36.jpg 36w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/A1-180x180.jpg 180w, https:\/\/www.allurealps.com\/wp-content\/uploads\/2026\/04\/A1-705x705.jpg 705w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kcelalw9-3-24b5673f0c690bb426a0f98f05d53d8c\">\n#top .av_textblock_section.av-kcelalw9-3-24b5673f0c690bb426a0f98f05d53d8c .avia_textblock{\nfont-size:14px;\n}\n<\/style>\n<section  class='av_textblock_section av-kcelalw9-3-24b5673f0c690bb426a0f98f05d53d8c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock text-team'  itemprop=\"text\" ><h4>Andrea Tassini<\/h4>\n<p class=\"titolo-elenco-experience\">Founder<\/p>\n<\/div><\/section><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_6'  class='avia-section av-1q8rd-15-3591a8f6714b98ba2c2d00ef8f137676 main_color avia-section-large avia-no-border-styling  avia-builder-el-29  el_after_av_section  el_before_av_slideshow_full  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-486'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1228h-11-42b7db1650218d5a5244966242ed8d92\">\n.flex_column.av-1228h-11-42b7db1650218d5a5244966242ed8d92{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1228h-11-42b7db1650218d5a5244966242ed8d92 av_one_fifth  avia-builder-el-30  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1228h-2-ba4756781c6d49461663809e44489d89\">\n.flex_column.av-1228h-2-ba4756781c6d49461663809e44489d89{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1228h-2-ba4756781c6d49461663809e44489d89 av_three_fifth  avia-builder-el-31  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-kcel4ow2-12-c0f205c3eb39a5ba09b576e6f0a9dfa6 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p data-start=\"1636\" data-end=\"1781\">Pi\u00f9 di una destination management company, Allure Alps \u00e8 un partner completo per la progettazione e la realizzazione di esperienze ed eventi di alto livello nelle Alpi.<\/p>\n<h2 style=\"text-align: center;\">Area<\/h2>\n<p style=\"text-align: center;\">Basati in Valle d&#8217;Aosta; presenti nele Alpi.<\/p>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1228h-1-8a4fc334b55940d7d946fcaab15ea892\">\n.flex_column.av-1228h-1-8a4fc334b55940d7d946fcaab15ea892{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1228h-1-8a4fc334b55940d7d946fcaab15ea892 av_one_fifth  avia-builder-el-33  el_after_av_three_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-34  el_after_av_section  el_before_av_postcontent   slider-not-first container_wrap fullsize'  ><div  class='avia-slideshow av-kceltwx5-b3d642bbc6067efd01cae383f029bf2e avia-slideshow-featured av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied   avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 30.714285714286%;'><li  class='avia-slideshow-slide av-kceltwx5-b3d642bbc6067efd01cae383f029bf2e__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-473 avia-img-lazy-loading-not-473\"  src=\"https:\/\/www.allurealps.com\/wp-content\/uploads\/2020\/07\/c-739-a-019-7-e-1-b-4-d-51-a-680-2-aa-24-cfb-6-f-8-c-1400x430.jpg\" width=\"1400\" height=\"430\" title='c-739-a-019-7-e-1-b-4-d-51-a-680-2-aa-24-cfb-6-f-8-c' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><\/ul><\/div><\/div>\n[av_section min_height='' min_height_pc='25' min_height_px='500px' padding='huge' custom_margin='0px' custom_margin_sync='true' color='alternate_color' background='bg_color' custom_bg='' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='http:\/\/www.allurealps.com\/wp-content\/uploads\/2020\/07\/isoipse-allure-copy.jpg' attachment='135' attachment_size='full' attach='scroll' position='center center' repeat='stretch' video='' video_ratio='16:9' overlay_opacity='0.5' overlay_color='' overlay_pattern='' overlay_custom_pattern='' shadow='no-border-styling' bottom_border='no-border-styling' bottom_border_diagonal_color='#333333' bottom_border_diagonal_direction='' bottom_border_style='' custom_arrow_bg='' id='' custom_class='' aria_label='' av_element_hidden_in_editor='0' av_uid='av-kcam1vg3']\r\n\r\n[av_hr class='invisible' icon_select='yes' icon='ue808' font='entypo-fontello' position='center' shadow='no-shadow' height='30' custom_border='av-border-thin' custom_width='50px' custom_margin_top='30px' custom_margin_bottom='30px' custom_border_color='' custom_icon_color='' av-desktop-hide='aviaTBav-desktop-hide' id='' custom_class='' av_uid='av-kcewxu2n' admin_preview_bg='']\r\n\r\n[av_heading heading='Sei interessato alle nostre esperienze?' tag='h2' style='blockquote modern-quote modern-centered' subheading_active='subheading_below' show_icon='' icon='note' font='svg_entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='18' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_dynamic='' link_target='' title_attr='' id='' custom_class='' template_class='' av_uid='av-kk2hjchn' sc_version='1.0' admin_preview_bg='']\r\nUn nostro agente dedicato ti assister\u00e0 per le tue esigenze\r\n[\/av_heading]\r\n\r\n[av_one_fourth first min_height='' vertical_alignment='' space='' row_boxshadow='' row_boxshadow_color='' row_boxshadow_width='10' custom_margin='' margin='0px' mobile_breaking='' border='' border_color='' radius='0px' padding='0px' column_boxshadow='' column_boxshadow_color='' column_boxshadow_width='10' background='bg_color' background_color='' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' animation='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' id='' custom_class='' aria_label='' av_uid='av-9l39k']\r\n\r\n[\/av_one_fourth][av_one_half min_height='' vertical_alignment='' space='' row_boxshadow='' row_boxshadow_color='' row_boxshadow_width='10' custom_margin='' margin='0px' mobile_breaking='' border='' border_color='' radius='0px' padding='0px' column_boxshadow='' column_boxshadow_color='' column_boxshadow_width='10' background='bg_color' background_color='' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' animation='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' id='' custom_class='' aria_label='' av_uid='av-95rho']\r\n\r\n[av_textblock size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' id='' custom_class='' av_uid='av-kcarf7z9' admin_preview_bg='']\r\n<p style=\"text-align: center;\">[contact-form-7 id=\"537\" title=\"Interessato nelle esperienze?\"]<\/p>\r\n[\/av_textblock]\r\n\r\n[\/av_one_half][av_one_fourth min_height='' vertical_alignment='' space='' row_boxshadow='' row_boxshadow_color='' row_boxshadow_width='10' custom_margin='' margin='0px' mobile_breaking='' border='' border_color='' radius='0px' padding='0px' column_boxshadow='' column_boxshadow_color='' column_boxshadow_width='10' background='bg_color' background_color='' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' animation='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' id='' custom_class='' aria_label='' av_uid='av-5hdio']\r\n\r\n[\/av_one_fourth][\/av_section][av_section min_height='' min_height_pc='25' min_height_px='500px' padding='huge' custom_margin='0px' custom_margin_sync='true' color='main_color' background='bg_color' custom_bg='#faf9f5' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='' attachment='' attachment_size='' attach='scroll' position='top left' repeat='no-repeat' video='' video_ratio='16:9' overlay_opacity='0.5' overlay_color='' overlay_pattern='' overlay_custom_pattern='' shadow='no-border-styling' bottom_border='no-border-styling' bottom_border_diagonal_color='#333333' bottom_border_diagonal_direction='' bottom_border_style='' custom_arrow_bg='' id='' custom_class='all-our-experiences' aria_label='' av_element_hidden_in_editor='0' av_uid='av-o6nl']\r\n\r\n[av_one_full first min_height='' vertical_alignment='' space='' row_boxshadow='' row_boxshadow_color='' row_boxshadow_width='10' custom_margin='' margin='0px' mobile_breaking='' border='' border_color='' radius='0px' padding='0px' column_boxshadow='' column_boxshadow_color='' column_boxshadow_width='10' background='bg_color' background_color='' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' animation='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' id='' custom_class='' aria_label='' av_uid='av-5hdio-2']\r\n\r\n[av_heading heading='Le nostre Esperienze' tag='h2' style='blockquote modern-quote' subheading_active='' show_icon='' icon='note' font='svg_entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_dynamic='' link_target='' title_attr='' id='' custom_class='' template_class='' av_uid='av-7k1fa' sc_version='1.0' admin_preview_bg=''][\/av_heading]\r\n\r\n[\/av_one_full][av_one_fourth first min_height='' vertical_alignment='' space='' row_boxshadow='' row_boxshadow_color='' row_boxshadow_width='10' custom_margin='' margin='0px' mobile_breaking='' border='' border_color='' radius='0px' padding='0px' column_boxshadow='' column_boxshadow_color='' column_boxshadow_width='10' background='bg_color' background_color='' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' animation='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' id='' custom_class='' aria_label='' av_uid='av-5hdio-1']\r\n\r\n[av_textblock size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' id='' custom_class='' av_uid='av-kcehvg6t' admin_preview_bg='']\r\n<div class=\"titolo-elenco-experience\">Nature<\/a>\r\n[\/av_textblock]\r\n\r\n[av_portfolio categories='5' date_filter='' date_filter_start='' date_filter_end='' date_filter_format='yy\/mm\/dd' sort='no' query_orderby='title' query_order='ASC' contents='title' preview_mode='auto' image_size='portfolio' columns='1' av-medium-columns='1' av-small-columns='1' av-mini-columns='1' one_column_template='special' items='74' paginate='no' linking='' id='' custom_class='elenco-esperienze-testo' av_uid='av-kcd5lg2b']\r\n\r\n[\/av_one_fourth][\/av_section]\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-486","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alpine Event &amp; Experience Agency | About Allure Alps<\/title>\n<meta name=\"description\" content=\"Allure Alps \u00e8 un\u2019agenzia specializzata in eventi ed esperienze di alto livello nelle Alpi. Scopri il nostro approccio e missione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.allurealps.com\/it\/about\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alpine Event &amp; Experience Agency | About Allure Alps\" \/>\n<meta property=\"og:description\" content=\"Allure Alps \u00e8 un\u2019agenzia specializzata in eventi ed esperienze di alto livello nelle Alpi. Scopri il nostro approccio e missione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.allurealps.com\/it\/about\/\" \/>\n<meta property=\"og:site_name\" content=\"Allure Alps\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T16:20:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.allurealps.com\\\/it\\\/about\\\/\",\"url\":\"https:\\\/\\\/www.allurealps.com\\\/it\\\/about\\\/\",\"name\":\"Alpine Event & Experience Agency | About Allure Alps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.allurealps.com\\\/it\\\/#website\"},\"datePublished\":\"2020-07-03T13:04:51+00:00\",\"dateModified\":\"2026-05-11T16:20:03+00:00\",\"description\":\"Allure Alps \u00e8 un\u2019agenzia specializzata in eventi ed esperienze di alto livello nelle Alpi. Scopri il nostro approccio e missione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.allurealps.com\\\/it\\\/about\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.allurealps.com\\\/it\\\/about\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.allurealps.com\\\/it\\\/about\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.allurealps.com\\\/it\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.allurealps.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.allurealps.com\\\/it\\\/\",\"name\":\"Allure Alps\",\"description\":\"Allure Alps is a DMC specialized in providing mountain experiences, personalized holidays, luxury accommodations and tailor-made services for private trips or corporate events\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.allurealps.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alpine Event & Experience Agency | About Allure Alps","description":"Allure Alps \u00e8 un\u2019agenzia specializzata in eventi ed esperienze di alto livello nelle Alpi. Scopri il nostro approccio e missione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.allurealps.com\/it\/about\/","og_locale":"it_IT","og_type":"article","og_title":"Alpine Event & Experience Agency | About Allure Alps","og_description":"Allure Alps \u00e8 un\u2019agenzia specializzata in eventi ed esperienze di alto livello nelle Alpi. Scopri il nostro approccio e missione.","og_url":"https:\/\/www.allurealps.com\/it\/about\/","og_site_name":"Allure Alps","article_modified_time":"2026-05-11T16:20:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.allurealps.com\/it\/about\/","url":"https:\/\/www.allurealps.com\/it\/about\/","name":"Alpine Event & Experience Agency | About Allure Alps","isPartOf":{"@id":"https:\/\/www.allurealps.com\/it\/#website"},"datePublished":"2020-07-03T13:04:51+00:00","dateModified":"2026-05-11T16:20:03+00:00","description":"Allure Alps \u00e8 un\u2019agenzia specializzata in eventi ed esperienze di alto livello nelle Alpi. Scopri il nostro approccio e missione.","breadcrumb":{"@id":"https:\/\/www.allurealps.com\/it\/about\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.allurealps.com\/it\/about\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.allurealps.com\/it\/about\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.allurealps.com\/it\/homepage\/"},{"@type":"ListItem","position":2,"name":"About us"}]},{"@type":"WebSite","@id":"https:\/\/www.allurealps.com\/it\/#website","url":"https:\/\/www.allurealps.com\/it\/","name":"Allure Alps","description":"Allure Alps is a DMC specialized in providing mountain experiences, personalized holidays, luxury accommodations and tailor-made services for private trips or corporate events","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.allurealps.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.allurealps.com\/it\/wp-json\/wp\/v2\/pages\/486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.allurealps.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.allurealps.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.allurealps.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.allurealps.com\/it\/wp-json\/wp\/v2\/comments?post=486"}],"version-history":[{"count":41,"href":"https:\/\/www.allurealps.com\/it\/wp-json\/wp\/v2\/pages\/486\/revisions"}],"predecessor-version":[{"id":3147,"href":"https:\/\/www.allurealps.com\/it\/wp-json\/wp\/v2\/pages\/486\/revisions\/3147"}],"wp:attachment":[{"href":"https:\/\/www.allurealps.com\/it\/wp-json\/wp\/v2\/media?parent=486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}